{"id":6,"date":"2022-05-17T21:39:04","date_gmt":"2022-05-17T21:39:04","guid":{"rendered":"https:\/\/www.hairandmakeupbyana.com\/es\/?page_id=6"},"modified":"2026-02-19T02:24:44","modified_gmt":"2026-02-19T02:24:44","slug":"home","status":"publish","type":"page","link":"https:\/\/www.hairandmakeupbyana.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2b323a&#8221; bg_image=&#8221;840&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; video_bg=&#8221;use_video&#8221; enable_video_color_overlay=&#8221;true&#8221; video_overlay_color=&#8221;rgba(160,1,1,0.13)&#8221; video_external=&#8221;https:\/\/www.youtube.com\/watch?v=TtnXDF68VcU&#8221; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221; color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;radial&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;bottom&#8221; shape_divider_height=&#8221;100px&#8221; shape_divider_bring_to_front=&#8221;true&#8221; bg_image_animation=&#8221;fade-in&#8221; shape_type=&#8221;curve_asym&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; translate_y=&#8221;250&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; delay=&#8221;600&#8243; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; next_section_color=&#8221;#ffffff&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;static&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-lg vc_hidden-md&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; left_padding_desktop=&#8221;35%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;35%&#8221; left_padding_tablet=&#8221;25%&#8221; constrain_group_4=&#8221;yes&#8221; right_padding_tablet=&#8221;25%&#8221; left_padding_phone=&#8221;12%&#8221; constrain_group_6=&#8221;yes&#8221; right_padding_phone=&#8221;12%&#8221; translate_y=&#8221;-50%&#8221; translate_x=&#8221;-50%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;absolute&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; top_position_desktop=&#8221;50%&#8221; left_position_desktop=&#8221;50%&#8221; min_width_desktop=&#8221;100%&#8221; zindex=&#8221;100&#8243; overflow=&#8221;visible&#8221; pointer_events=&#8221;none&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#dd3333&#8243; text_color=&#8221;#ffffff&#8221; style=&#8221;half_text&#8221; custom_font_size=&#8221;35px&#8221;]\n<p style=\"text-align: center;\">Bienvenidos a<\/p>\n<h1 style=\"text-align: center;\">Hair And Makeup <em>By Ana<\/em><\/h1>\n[\/nectar_highlighted_text][nectar_cta btn_style=&#8221;next-section&#8221; btn_type=&#8221;minimal-arrow&#8221; next_section_color=&#8221;#ffffff&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221;][\/vc_column_inner][\/vc_row_inner][carousel script=&#8221;simple_slider&#8221; simple_slider_sizing=&#8221;aspect_ratio&#8221; simple_slider_aspect_ratio=&#8221;4-3&#8243; simple_slider_touch_indicator=&#8221;true&#8221; simple_slider_touch_indicator_bg_color=&#8221;#dd3333&#8243; simple_slider_touch_indicator_icon_color=&#8221;#000000&#8243; simple_slider_transition_type=&#8221;slide&#8221; simple_slider_parallax=&#8221;true&#8221; simple_slider_wrap=&#8221;true&#8221; simple_slider_min_height=&#8221;950&#8243;][item simple_slider_bg_image_url=&#8221;1773&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711564-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711564-1&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1781&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(10,10,10,0.5)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711573-8&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711573-6&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1782&#8243; simple_slider_bg_image_position=&#8221;center-top&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711577-6&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711577-3&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1784&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711581-7&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711581-5&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1785&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711589-5&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711589-4&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1395&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711596-4&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711596-2&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1396&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711604-2&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711605-7&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1397&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711615-10&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711615-4&#8243;][vc_column_text][\/vc_column_text][\/item][item simple_slider_bg_image_url=&#8221;1398&#8243; simple_slider_bg_image_position=&#8221;center-bottom&#8221; simple_slider_font_color=&#8221;#ffffff&#8221; simple_slider_color_overlay=&#8221;rgba(0,0,0,0.78)&#8221; simple_slider_overlay_strength=&#8221;0.3&#8243; simple_slider_bg_image_loading=&#8221;default&#8221; flickity_bg_image_loading=&#8221;default&#8221; flex_gap_desktop=&#8221;10px&#8221; flickity_item_link_type=&#8221;regular&#8221; simple_slider_gradient_direction=&#8221;left_to_right&#8221; bg_image_url=&#8221;&#8221; bg_image_position=&#8221;default&#8221; image_url=&#8221;&#8221; id=&#8221;1771467711628-7&#8243; title=&#8221;Item&#8221; tab_id=&#8221;1771467711628-3&#8243;][vc_column_text][\/vc_column_text][\/item][\/carousel][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;6%&#8221; bottom_padding=&#8221;2%&#8221; left_padding_desktop=&#8221;10%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;10%&#8221; top_padding_tablet=&#8221;20%&#8221; bottom_padding_tablet=&#8221;10%&#8221; constrain_group_8=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;padding-4-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; column_border_style=&#8221;dashed&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; right_padding_desktop=&#8221;20%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h2&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; font_size=&#8221;7vh&#8221; text_content=&#8221;Hair and Makeup By Ana&#8221;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;15&#8243; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Somos un sal\u00f3n de servicio de belleza con un equipo de maquillistas y estilistas profesionales para novias y eventos sociales que te ayudar\u00e1n a lucir lo mejor posible en las fechas m\u00e1s importantes de tu vida.&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|line_height:1.8&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;Creemos que toda mujer deben sentirse hermosa, segura y maravillosa en cualquier momento especial de su vida. Nuestro principal objetivo es escuchar a nuestros clientes y ayudarlos a lograr la visi\u00f3n de su imaginaci\u00f3n mientras disfrutan de una experiencia placentera, libre de estr\u00e9s y c\u00e1lida.&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|line_height:1.8&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_cta btn_style=&#8221;see-through&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;new_tab&#8221; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#c40360&#8243; text_color=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;right&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;left&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;HAZ UNA CITA&#8221; padding_top=&#8221;20&#8243; padding_bottom=&#8221;20&#8243; padding_left=&#8221;25&#8243; padding_right=&#8221;25&#8243; url=&#8221;https:\/\/book.squareup.com\/appointments\/17p4xrvscctvrn\/location\/L6CN9E5AN6PSX\/services&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243; text=&#8221;\u00bfEst\u00e1s lista para verte de lo mejor?&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;80px&#8221; top_padding_phone=&#8221;40px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221; custom_height=&#8221;25px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#dd3333&#8243; text_color=&#8221;#828282&#8243; style=&#8221;half_text&#8221; custom_font_size=&#8221;35px&#8221;]\n<h2 style=\"text-align: center;\">Nuestros Servicios de Peinado<br \/>\ny Maquillaje Son<\/h2>\n[\/nectar_highlighted_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;default&#8221; custom_height=&#8221;25px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; constrain_group_2=&#8221;yes&#8221; constrain_group_7=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;content-shadow&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;1747&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.3&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;full&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/peinado-y-maquillaje-para-bodas\/&#8221; min_height=&#8221;635&#8243;]\n<h2>Peinado y Maquillaje Bodas<\/h2>\n[\/fancy_box][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;156&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.3&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;Medium&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/peinado-maquillaje-eventos-sociales-prom-invitados-reuniones\/&#8221; min_height=&#8221;200&#8243;]\n<h3>Peinado y Maquillaje Sociales<\/h3>\n[\/fancy_box][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;1780&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.3&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;full&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/peinado-maquillaje-quinceanera-sweet-16-debutante\/&#8221; min_height=&#8221;200&#8243;]\n<h3>Peinado y Maquillaje Quincea\u00f1era\/Sweet 16<\/h3>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin=&#8221;25px&#8221; constrain_group_1=&#8221;yes&#8221; bottom_margin=&#8221;25px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;294&#8243; image_size=&#8221;custom&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Grow In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; custom_image_size=&#8221;1400&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_2=&#8221;yes&#8221; constrain_group_7=&#8221;yes&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; class=&#8221;content-shadow&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;20px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;193&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.3&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;full&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/tratamientos-lujosos-termicos-nanoplastia-botox-capilar\/&#8221; min_height=&#8221;200&#8243;]\n<h2>Tratamientos Lujosos<\/h2>\n[\/fancy_box][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221; offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;25px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;190&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.3&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;full&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/peinado-maquillaje-video-foto\/&#8221; min_height=&#8221;200&#8243;]\n<h3>Peinado y Maquillaje para Video y Foto<\/h3>\n[\/fancy_box][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;top-bottom&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][fancy_box box_style=&#8221;parallax_hover&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;869&#8243; parallax_hover_box_alignment=&#8221;bottom&#8221; parallax_hover_box_overlay_opacity=&#8221;0&#8243; parallax_hover_box_overlay_opacity_hover=&#8221;0.2&#8243; border_radius=&#8221;10px&#8221; image_loading=&#8221;default&#8221; image_size=&#8221;full&#8221; link_url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/servicios\/servicios-de-salon\/&#8221; min_height=&#8221;650&#8243;]\n<h2>Servicios de Sal\u00f3n<\/h2>\n[\/fancy_box][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;316&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;left bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; left_padding_desktop=&#8221;5%&#8221; right_padding_desktop=&#8221;5%&#8221; top_margin=&#8221;7%&#8221; constrain_group_7=&#8221;yes&#8221; bottom_margin=&#8221;7%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#000000&#8243; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; enable_shape_divider=&#8221;true&#8221; shape_divider_position=&#8221;both&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;medium_fast&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;curve_asym&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; highlight_color=&#8221;#dd3333&#8243; text_color=&#8221;#ffffff&#8221; style=&#8221;half_text&#8221; custom_font_size=&#8221;55px&#8221;]\n<h2 style=\"text-align: center;\">El estilo es una manera de decir <em>qui\u00e9n eres<\/em> sin decir nada en absoluto.<\/h2>\n[\/nectar_highlighted_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;50px&#8221;][nectar_cta btn_style=&#8221;see-through&#8221; heading_tag=&#8221;h5&#8243; link_type=&#8221;new_tab&#8221; button_color=&#8221;accent-color&#8221; button_color_hover=&#8221;#c40360&#8243; text_color=&#8221;#ffffff&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;center&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;center&#8221; constrain_group_1=&#8221;yes&#8221; constrain_group_3=&#8221;yes&#8221; constrain_group_4=&#8221;yes&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; link_text=&#8221;HAZ UNA CITA&#8221; padding_top=&#8221;20&#8243; padding_bottom=&#8221;20&#8243; padding_left=&#8221;50&#8243; padding_right=&#8221;50&#8243; url=&#8221;https:\/\/book.squareup.com\/appointments\/17p4xrvscctvrn\/location\/L6CN9E5AN6PSX\/services&#8221; margin_top=&#8221;20&#8243; margin_bottom=&#8221;20&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/4&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;3%&#8221; bottom_padding=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;Servicios de peinado y maquillaje para toda ocasi\u00f3n&#8221; font_container=&#8221;tag:h1|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;35px&#8221;][nectar_text_inline_images media_type=&#8221;images&#8221; images=&#8221;337,338,339,336&#8243; image_size=&#8221;medium_featured&#8221; image_effect=&#8221;circle_fade_in&#8221; media_roundness=&#8221;0px&#8221; inherit_typography_from=&#8221;default&#8221; image_loading=&#8221;default&#8221; font_size_desktop=&#8221;25px&#8221; font_line_height=&#8221;50px&#8221;]Nuestro equipo de profesionales de peinado y maquillaje, est\u00e1n dirigidos por la propia Ana * y est\u00e1n listos para dise\u00f1ar looks elegantes, modernos o naturales para resaltar la belleza natural y la personalidad de cada * cliente, complementando * sus caracter\u00edsticas \u00fanicas *.[\/nectar_text_inline_images][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#dd3333&#8243; hover_color_override=&#8221;#dd3333&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;M\u00c1S SOBRE NOSOTROS&#8221; url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/sobre-peinado-y-maquillaje-por-ana\/&#8221; margin_top=&#8221;25px&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#dd3333&#8243; hover_color_override=&#8221;#dd3333&#8243; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;none&#8221; text=&#8221;LO QUE NUESTROS CLIENTES DICEN&#8221; url=&#8221;https:\/\/www.hairandmakeupbyana.com\/es\/contactanos\/#testimonials&#8221; margin_top=&#8221;25px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;1122&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;zoom&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1707291379997{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<div id=\"sb_instagram\"  class=\"sbi sbi_mob_col_2 sbi_tab_col_2 sbi_col_3 sbi_width_resp\" style=\"padding-bottom: 10px;\"\t data-feedid=\"*1\"  data-res=\"auto\" data-cols=\"3\" data-colsmobile=\"2\" data-colstablet=\"2\" data-num=\"3\" data-nummobile=\"3\" data-item-padding=\"5\"\t data-shortcode-atts=\"{&quot;feed&quot;:&quot;1&quot;}\"  data-postid=\"6\" data-locatornonce=\"96c035f8ab\" data-imageaspectratio=\"1:1\" data-sbi-flags=\"favorLocal\">\n\t<div class=\"sb_instagram_header \"   >\n\t<a class=\"sbi_header_link\" target=\"_blank\" rel=\"nofollow noopener\" href=\"https:\/\/www.instagram.com\/hairandmakeupbyana\/\" title=\"@hairandmakeupbyana\">\n\t\t<div class=\"sbi_header_text sbi_no_bio\">\n\t\t\t<div class=\"sbi_header_img\"  data-avatar-url=\"https:\/\/scontent-ord5-1.xx.fbcdn.net\/v\/t51.82787-15\/601356088_18545085790059833_3758556688937999737_n.jpg?_nc_cat=108&amp;ccb=1-7&amp;_nc_sid=7d201b&amp;_nc_ohc=VcDLli23xm0Q7kNvwGrrqie&amp;_nc_oc=AdoIzG0KXwihO8RjXIPhDgERFDp_Zui2ezG8EJaMs5n-ZRyVqFBEDMM7Bq8y6MZuhyI&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-1.xx&amp;edm=AL-3X8kEAAAA&amp;_nc_gid=P88k6qQyZvF485oU-DR8Ow&amp;oh=00_AQAIqg4iDeZlqk0KYIoIBy41ihDMkknVPbA5fF3VJehvAA&amp;oe=6A5D9A07\">\n\t\t\t\t\t\t\t\t\t<div class=\"sbi_header_img_hover\"  ><svg class=\"sbi_new_logo fa-instagram fa-w-14\" aria-hidden=\"true\" data-fa-processed=\"\" aria-label=\"Instagram\" data-prefix=\"fab\" data-icon=\"instagram\" role=\"img\" viewBox=\"0 0 448 512\">\n                    <path fill=\"currentColor\" d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path>\n                <\/svg><\/div>\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/www.hairandmakeupbyana.com\/es\/wp-content\/uploads\/sb-instagram-feed-images\/hairandmakeupbyana.webp\" alt=\"\" width=\"50\" height=\"50\">\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"sbi_feedtheme_header_text\">\n\t\t\t\t<h3>hairandmakeupbyana<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n\n\t<div id=\"sbi_images\"  style=\"gap: 10px;\">\n\t\t<div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18015450008863185\" data-date=\"1783663458\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DamejX3usKD\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-ord5-2.cdninstagram.com\/v\/t51.82787-15\/743805574_18600741532059833_6180835873927793350_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=104&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=WXOigz_nuZ4Q7kNvwHv5fsC&#038;_nc_oc=AdoSnBB02uGVQy425-qToEwXvNAX6Y49leJMR-jGvTOgio4ygDrCVk0CboKPfnUOye0&#038;_nc_zt=23&#038;_nc_ht=scontent-ord5-2.cdninstagram.com&#038;edm=AM6HXa8EAAAA&#038;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&#038;_nc_tpa=Q5bMBQFS5qnHWHpeva4gXo8YWVYfswmlJ1_vMBXPIUC7QrdqKba2soPNrQmnc0RiUZevHSOG-ruqeuti&#038;oh=00_AQBP8hAgu1UssR8x0sFZcYJh9Wa36HAFn_I5SsRp3AG8Ow&#038;oe=6A5D96F9\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-ord5-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/743805574_18600741532059833_6180835873927793350_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=WXOigz_nuZ4Q7kNvwHv5fsC&amp;_nc_oc=AdoSnBB02uGVQy425-qToEwXvNAX6Y49leJMR-jGvTOgio4ygDrCVk0CboKPfnUOye0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-2.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQFS5qnHWHpeva4gXo8YWVYfswmlJ1_vMBXPIUC7QrdqKba2soPNrQmnc0RiUZevHSOG-ruqeuti&amp;oh=00_AQBP8hAgu1UssR8x0sFZcYJh9Wa36HAFn_I5SsRp3AG8Ow&amp;oe=6A5D96F9&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-ord5-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/743805574_18600741532059833_6180835873927793350_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=WXOigz_nuZ4Q7kNvwHv5fsC&amp;_nc_oc=AdoSnBB02uGVQy425-qToEwXvNAX6Y49leJMR-jGvTOgio4ygDrCVk0CboKPfnUOye0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-2.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQFS5qnHWHpeva4gXo8YWVYfswmlJ1_vMBXPIUC7QrdqKba2soPNrQmnc0RiUZevHSOG-ruqeuti&amp;oh=00_AQBP8hAgu1UssR8x0sFZcYJh9Wa36HAFn_I5SsRp3AG8Ow&amp;oe=6A5D96F9&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-ord5-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/743805574_18600741532059833_6180835873927793350_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=WXOigz_nuZ4Q7kNvwHv5fsC&amp;_nc_oc=AdoSnBB02uGVQy425-qToEwXvNAX6Y49leJMR-jGvTOgio4ygDrCVk0CboKPfnUOye0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-2.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQFS5qnHWHpeva4gXo8YWVYfswmlJ1_vMBXPIUC7QrdqKba2soPNrQmnc0RiUZevHSOG-ruqeuti&amp;oh=00_AQBP8hAgu1UssR8x0sFZcYJh9Wa36HAFn_I5SsRp3AG8Ow&amp;oe=6A5D96F9&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-ord5-2.cdninstagram.com\\\/v\\\/t51.82787-15\\\/743805574_18600741532059833_6180835873927793350_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=104&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=WXOigz_nuZ4Q7kNvwHv5fsC&amp;_nc_oc=AdoSnBB02uGVQy425-qToEwXvNAX6Y49leJMR-jGvTOgio4ygDrCVk0CboKPfnUOye0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-2.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQFS5qnHWHpeva4gXo8YWVYfswmlJ1_vMBXPIUC7QrdqKba2soPNrQmnc0RiUZevHSOG-ruqeuti&amp;oh=00_AQBP8hAgu1UssR8x0sFZcYJh9Wa36HAFn_I5SsRp3AG8Ow&amp;oe=6A5D96F9&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">A fun and inspiring experience where young ladies<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hairandmakeupbyana.com\/es\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"A fun and inspiring experience where young ladies will learn how to enhance their natural beauty while building confidence in a welcoming and hands-on environment.\n\n\ud83d\udcc5 July 27, 2026\n\u23f0 11:00 AM \u2013 4:00 PM\n\ud83d\udccd Hair &amp; Makeup by Ana\n740 Barchester Dr.\nSan Antonio, TX 78216\n\nWhat\u2019s Included:\n\u2728New set of makeup brushes \n\u2728 Hands-on makeup instruction and demonstrations\n\u2728 Lunch\n\u2728 Diploma of Participation\n\u2728 Fun surprises\n\n\ud83d\udd17https:\/\/www.hairandmakeupbyana.com\/self-makeup-workshop-for-teens\/#booking-form\n\n\ud83d\udcf2DM\n\ud83d\udcde (210) 500-2240\n\ud83c\udf10 hairandmakeupbyana.com\n\n\u2728 Limited spots available. \nReserve yours today! \ud83d\udc95\n\n#TeenMakeupClass \n#MakeupForTeens \n#GlowUp \n#SanAntonioTeens\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18421373074179999\" data-date=\"1783659895\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DamThHDOkdO\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-ord5-3.cdninstagram.com\/v\/t51.82787-15\/742416925_18600729094059833_5610835306802085923_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=110&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=1YoeWFdUaEgQ7kNvwHHS1lS&#038;_nc_oc=AdrygSZZELzNitRV2WUJl0Vh1dGFXnohlrP-kg7Mhlm8CvXykYMdu1WA2Nxwq-f1Iz0&#038;_nc_zt=23&#038;_nc_ht=scontent-ord5-3.cdninstagram.com&#038;edm=AM6HXa8EAAAA&#038;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&#038;_nc_tpa=Q5bMBQGuA9xVqvEhPKxIuynb4qfXsiFBndlRp_f26YhlG_57RT4iZqp4DMYG3RrFrXCFvzcFvLbAwQ6x&#038;oh=00_AQA3C_b0Bao5AR438fMstFkzkI4FKnfQqiBwzr40R69kOQ&#038;oe=6A5DA42B\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-ord5-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/742416925_18600729094059833_5610835306802085923_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=110&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=1YoeWFdUaEgQ7kNvwHHS1lS&amp;_nc_oc=AdrygSZZELzNitRV2WUJl0Vh1dGFXnohlrP-kg7Mhlm8CvXykYMdu1WA2Nxwq-f1Iz0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-3.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQGuA9xVqvEhPKxIuynb4qfXsiFBndlRp_f26YhlG_57RT4iZqp4DMYG3RrFrXCFvzcFvLbAwQ6x&amp;oh=00_AQA3C_b0Bao5AR438fMstFkzkI4FKnfQqiBwzr40R69kOQ&amp;oe=6A5DA42B&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-ord5-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/742416925_18600729094059833_5610835306802085923_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=110&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=1YoeWFdUaEgQ7kNvwHHS1lS&amp;_nc_oc=AdrygSZZELzNitRV2WUJl0Vh1dGFXnohlrP-kg7Mhlm8CvXykYMdu1WA2Nxwq-f1Iz0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-3.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQGuA9xVqvEhPKxIuynb4qfXsiFBndlRp_f26YhlG_57RT4iZqp4DMYG3RrFrXCFvzcFvLbAwQ6x&amp;oh=00_AQA3C_b0Bao5AR438fMstFkzkI4FKnfQqiBwzr40R69kOQ&amp;oe=6A5DA42B&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-ord5-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/742416925_18600729094059833_5610835306802085923_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=110&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=1YoeWFdUaEgQ7kNvwHHS1lS&amp;_nc_oc=AdrygSZZELzNitRV2WUJl0Vh1dGFXnohlrP-kg7Mhlm8CvXykYMdu1WA2Nxwq-f1Iz0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-3.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQGuA9xVqvEhPKxIuynb4qfXsiFBndlRp_f26YhlG_57RT4iZqp4DMYG3RrFrXCFvzcFvLbAwQ6x&amp;oh=00_AQA3C_b0Bao5AR438fMstFkzkI4FKnfQqiBwzr40R69kOQ&amp;oe=6A5DA42B&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-ord5-3.cdninstagram.com\\\/v\\\/t51.82787-15\\\/742416925_18600729094059833_5610835306802085923_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=110&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=1YoeWFdUaEgQ7kNvwHHS1lS&amp;_nc_oc=AdrygSZZELzNitRV2WUJl0Vh1dGFXnohlrP-kg7Mhlm8CvXykYMdu1WA2Nxwq-f1Iz0&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-3.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=zF8-2-VJsavYRDtH_VVdyg&amp;_nc_tpa=Q5bMBQGuA9xVqvEhPKxIuynb4qfXsiFBndlRp_f26YhlG_57RT4iZqp4DMYG3RrFrXCFvzcFvLbAwQ6x&amp;oh=00_AQA3C_b0Bao5AR438fMstFkzkI4FKnfQqiBwzr40R69kOQ&amp;oe=6A5DA42B&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">Detr\u00e1s de cada maquillaje y peinado impecable hay<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hairandmakeupbyana.com\/es\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"Detr\u00e1s de cada maquillaje y peinado impecable hay a\u00f1os de experiencia, preparaci\u00f3n y dedicaci\u00f3n. \u2728 \n\nLo que inviertes no es solo un servicio; es la tranquilidad de saber que ese d\u00eda te ver\u00e1s y te sentir\u00e1s espectacular. \ud83d\udc84\ud83e\udd0d\n\nBehind every flawless glam is years of experience, precision, and passion. \u2728 \n\nWhat you\u2019re paying for isn\u2019t just makeup and hair, it\u2019s the confidence you leave with. \ud83d\udc84\ud83e\udd0d\n\n* #SanAntonioMakeupArtist\n* #BridalAndBeauty\n* #ProfessionalGlam\n* #HairAndMakeupByAna\n* #LuxuryBeautyServices\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div><div class=\"sbi_item sbi_type_video sbi_new sbi_transition\"\n\tid=\"sbi_18063995507541499\" data-date=\"1783447218\">\n\t<div class=\"sbi_photo_wrap\">\n\t\t<a class=\"sbi_photo\" href=\"https:\/\/www.instagram.com\/reel\/DagA9DEuhqQ\/\" target=\"_blank\" rel=\"noopener nofollow\" data-full-res=\"https:\/\/scontent-ord5-1.cdninstagram.com\/v\/t51.82787-15\/735786325_18600052018059833_842851018191237543_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=106&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=qqAL3Lfn-f0Q7kNvwHQa3HA&#038;_nc_oc=AdqiOFq5TrDuhuw4z5VTqXCnWGAyQdn5KLXuBztZCIIc20SMVGBLW476pVapMatjTIQ&#038;_nc_zt=23&#038;_nc_ht=scontent-ord5-1.cdninstagram.com&#038;edm=AM6HXa8EAAAA&#038;_nc_gid=Q6TFvZXxuefLm22BUcfxXw&#038;_nc_tpa=Q5bMBQEc1HVH7YI6AnrPfPRdzUN-OxVWqK-2pfGhH79Fi3TK9qVr1vPye6IBsfzGOgULnksa03H5frSo&#038;oh=00_AQBQ_Vz8McKv31zzg_vUPd9opN3uHEZjZ3LsnI6NPN1aNg&#038;oe=6A5DA992\" data-img-src-set=\"{&quot;d&quot;:&quot;https:\\\/\\\/scontent-ord5-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/735786325_18600052018059833_842851018191237543_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qqAL3Lfn-f0Q7kNvwHQa3HA&amp;_nc_oc=AdqiOFq5TrDuhuw4z5VTqXCnWGAyQdn5KLXuBztZCIIc20SMVGBLW476pVapMatjTIQ&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-1.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=Q6TFvZXxuefLm22BUcfxXw&amp;_nc_tpa=Q5bMBQEc1HVH7YI6AnrPfPRdzUN-OxVWqK-2pfGhH79Fi3TK9qVr1vPye6IBsfzGOgULnksa03H5frSo&amp;oh=00_AQBQ_Vz8McKv31zzg_vUPd9opN3uHEZjZ3LsnI6NPN1aNg&amp;oe=6A5DA992&quot;,&quot;150&quot;:&quot;https:\\\/\\\/scontent-ord5-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/735786325_18600052018059833_842851018191237543_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qqAL3Lfn-f0Q7kNvwHQa3HA&amp;_nc_oc=AdqiOFq5TrDuhuw4z5VTqXCnWGAyQdn5KLXuBztZCIIc20SMVGBLW476pVapMatjTIQ&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-1.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=Q6TFvZXxuefLm22BUcfxXw&amp;_nc_tpa=Q5bMBQEc1HVH7YI6AnrPfPRdzUN-OxVWqK-2pfGhH79Fi3TK9qVr1vPye6IBsfzGOgULnksa03H5frSo&amp;oh=00_AQBQ_Vz8McKv31zzg_vUPd9opN3uHEZjZ3LsnI6NPN1aNg&amp;oe=6A5DA992&quot;,&quot;320&quot;:&quot;https:\\\/\\\/scontent-ord5-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/735786325_18600052018059833_842851018191237543_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qqAL3Lfn-f0Q7kNvwHQa3HA&amp;_nc_oc=AdqiOFq5TrDuhuw4z5VTqXCnWGAyQdn5KLXuBztZCIIc20SMVGBLW476pVapMatjTIQ&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-1.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=Q6TFvZXxuefLm22BUcfxXw&amp;_nc_tpa=Q5bMBQEc1HVH7YI6AnrPfPRdzUN-OxVWqK-2pfGhH79Fi3TK9qVr1vPye6IBsfzGOgULnksa03H5frSo&amp;oh=00_AQBQ_Vz8McKv31zzg_vUPd9opN3uHEZjZ3LsnI6NPN1aNg&amp;oe=6A5DA992&quot;,&quot;640&quot;:&quot;https:\\\/\\\/scontent-ord5-1.cdninstagram.com\\\/v\\\/t51.82787-15\\\/735786325_18600052018059833_842851018191237543_n.jpg?stp=dst-jpg_e35_tt6&amp;_nc_cat=106&amp;ccb=7-5&amp;_nc_sid=18de74&amp;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&amp;_nc_ohc=qqAL3Lfn-f0Q7kNvwHQa3HA&amp;_nc_oc=AdqiOFq5TrDuhuw4z5VTqXCnWGAyQdn5KLXuBztZCIIc20SMVGBLW476pVapMatjTIQ&amp;_nc_zt=23&amp;_nc_ht=scontent-ord5-1.cdninstagram.com&amp;edm=AM6HXa8EAAAA&amp;_nc_gid=Q6TFvZXxuefLm22BUcfxXw&amp;_nc_tpa=Q5bMBQEc1HVH7YI6AnrPfPRdzUN-OxVWqK-2pfGhH79Fi3TK9qVr1vPye6IBsfzGOgULnksa03H5frSo&amp;oh=00_AQBQ_Vz8McKv31zzg_vUPd9opN3uHEZjZ3LsnI6NPN1aNg&amp;oe=6A5DA992&quot;}\">\n\t\t\t<span class=\"sbi-screenreader\">\u2728 Summer is the perfect time to learn something ne<\/span>\n\t\t\t\t\t\t<svg style=\"color: rgba(255,255,255,1)\" class=\"svg-inline--fa fa-play fa-w-14 sbi_playbtn\" aria-label=\"Play\" aria-hidden=\"true\" data-fa-processed=\"\" data-prefix=\"fa\" data-icon=\"play\" role=\"presentation\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"><\/path><\/svg>\t\t\t<img decoding=\"async\" src=\"https:\/\/www.hairandmakeupbyana.com\/es\/wp-content\/plugins\/instagram-feed\/img\/placeholder.png\" alt=\"\u2728 Summer is the perfect time to learn something new! \ud83d\udc96\n\nCalling all young ladies on summer break! \nIf you\u2019ve always wanted to learn how to do your own makeup, this workshop is for you!\n\nJoin us for a fun, hands-on beauty experience where you\u2019ll learn beginner-friendly makeup techniques, beauty tips, and how to enhance your natural beauty with confidence.\n\nYou\u2019ll enjoy an exciting day filled with learning, creativity, new friendships, refreshments, a certificate of participation, a keepsake photo, and special surprises! \ud83d\udc84\u2728\n\n\u2728 Teen Self-Makeup Class \u2728\n\nA fun class designed to help teens learn natural makeup techniques, proper skincare, and how to feel confident using the right products for their age. \ud83d\udc84\ud83d\udc95\n\n\ud83d\udcf2 For more information or to reserve your spot:\n\u2022 WhatsApp: (210) 500-2240\n\u2022 DM\n\n\u2728 Limited spots available! \ud83d\udc95\n\n* #TeenMakeupClass\n* #SanAntonioTeens\n* #TeenBeauty\n* #MakeupForTeens\n* #SanAntonioMoms\" aria-hidden=\"true\">\n\t\t<\/a>\n\t<\/div>\n<\/div>\t<\/div>\n\n\t<div id=\"sbi_load\" >\n\n\t\n\t\n<\/div>\n\t\t<span class=\"sbi_resized_image_data\" data-feed-id=\"*1\"\n\t\t  data-resized=\"{&quot;18063995507541499&quot;:{&quot;id&quot;:&quot;735786325_18600052018059833_842851018191237543_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18421373074179999&quot;:{&quot;id&quot;:&quot;742416925_18600729094059833_5610835306802085923_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;},&quot;18015450008863185&quot;:{&quot;id&quot;:&quot;743805574_18600741532059833_6180835873927793350_n&quot;,&quot;ratio&quot;:&quot;0.56&quot;,&quot;sizes&quot;:{&quot;full&quot;:640,&quot;low&quot;:320,&quot;thumb&quot;:150},&quot;extension&quot;:&quot;.webp&quot;}}\">\n\t<\/span>\n\t<\/div>\n\n[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1655335236864{margin-top: 0px !important;padding-top: 0px !important;}&#8221;]\n<p style=\"text-align: right;\"><span style=\"color: #525252;\"><em>Checa nuestro trabajo m\u00e1s reciente en <a href=\"https:\/\/www.instagram.com\/hairandmakeupbyana\/\" target=\"_blank\" rel=\"noopener\">INSTAGRAM<\/a><\/em><\/span><\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;Full Width Line&#8221; line_thickness=&#8221;1&#8243; divider_color=&#8221;extra-color-3&#8243; custom_height=&#8221;25px&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#2b323a&#8221; bg_image=&#8221;840&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;center top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; full_height=&#8221;yes&#8221; video_bg=&#8221;use_video&#8221; enable_video_color_overlay=&#8221;true&#8221; video_overlay_color=&#8221;rgba(160,1,1,0.13)&#8221; video_external=&#8221;https:\/\/www.youtube.com\/watch?v=TtnXDF68VcU&#8221; background_video_loading=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;100&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;hidden&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-6","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/pages\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/comments?post=6"}],"version-history":[{"count":2,"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/pages\/6\/revisions"}],"predecessor-version":[{"id":1868,"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/pages\/6\/revisions\/1868"}],"wp:attachment":[{"href":"https:\/\/www.hairandmakeupbyana.com\/es\/wp-json\/wp\/v2\/media?parent=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}